{"id":5593,"date":"2024-11-10T10:47:39","date_gmt":"2024-11-10T09:47:39","guid":{"rendered":"https:\/\/www.ummto.dz\/fdsp\/?p=5593"},"modified":"2024-11-10T12:02:49","modified_gmt":"2024-11-10T11:02:49","slug":"liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024","status":"publish","type":"post","link":"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/","title":{"rendered":"Liste Provisoire des Candidats pour les Elections de la Cours Constitutionnelle du 07.12.2024."},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb type=\u00a0\u00bb4_4&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>Liste provisoire des candidats pour les \u00e9lections de la cours constitutionnelle\u00a0 du 07.12.2024. voir ici <a href=\"https:\/\/www.ummto.dz\/fdsp\/wp-content\/uploads\/2024\/11\/Listes-des-candidats.pdf\" rel=\"attachment wp-att-5597\">Listes des candidats<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liste provisoire des candidats pour les \u00e9lections de la cours constitutionnelle\u00a0 du 07.12.2024. voir ici Listes des candidats<\/p>\n","protected":false},"author":5,"featured_media":5049,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[7,11,12],"tags":[],"class_list":["post-5593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-new-dep-droit","category-new-dep-sc-politique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Liste Provisoire des Candidats pour les Elections de la Cours Constitutionnelle du 07.12.2024. - Facult\u00e9 De Droit Et Des Sciences Politiques<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liste Provisoire des Candidats pour les Elections de la Cours Constitutionnelle du 07.12.2024. - Facult\u00e9 De Droit Et Des Sciences Politiques\" \/>\n<meta property=\"og:description\" content=\"Liste provisoire des candidats pour les \u00e9lections de la cours constitutionnelle\u00a0 du 07.12.2024. voir ici Listes des candidats\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Facult\u00e9 De Droit Et Des Sciences Politiques\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-10T09:47:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-10T11:02:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ummto.dz\/fdsp\/wp-content\/uploads\/2023\/10\/avis.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"510\" \/>\n\t<meta property=\"og:image:height\" content=\"336\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"FDSP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"FDSP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\\\/\"},\"author\":{\"name\":\"FDSP\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/#\\\/schema\\\/person\\\/a868b9830e33c4360cb22a4100c4c7e0\"},\"headline\":\"Liste Provisoire des Candidats pour les Elections de la Cours Constitutionnelle du 07.12.2024.\",\"datePublished\":\"2024-11-10T09:47:39+00:00\",\"dateModified\":\"2024-11-10T11:02:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\\\/\"},\"wordCount\":100,\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/avis.webp\",\"articleSection\":[\"Actualit\u00e9\",\"dep droit\",\"dep-politique\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\\\/\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\\\/\",\"name\":\"Liste Provisoire des Candidats pour les Elections de la Cours Constitutionnelle du 07.12.2024. - Facult\u00e9 De Droit Et Des Sciences Politiques\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/avis.webp\",\"datePublished\":\"2024-11-10T09:47:39+00:00\",\"dateModified\":\"2024-11-10T11:02:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/#\\\/schema\\\/person\\\/a868b9830e33c4360cb22a4100c4c7e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/avis.webp\",\"contentUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/avis.webp\",\"width\":510,\"height\":336},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Liste Provisoire des Candidats pour les Elections de la Cours Constitutionnelle du 07.12.2024.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/#website\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/\",\"name\":\"Facult\u00e9 De Droit Et Des Sciences Politiques\",\"description\":\"Facult\u00e9 de Droit\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/#\\\/schema\\\/person\\\/a868b9830e33c4360cb22a4100c4c7e0\",\"name\":\"FDSP\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fdsp\\\/author\\\/fdsp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Liste Provisoire des Candidats pour les Elections de la Cours Constitutionnelle du 07.12.2024. - Facult\u00e9 De Droit Et Des Sciences Politiques","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/","og_locale":"fr_FR","og_type":"article","og_title":"Liste Provisoire des Candidats pour les Elections de la Cours Constitutionnelle du 07.12.2024. - Facult\u00e9 De Droit Et Des Sciences Politiques","og_description":"Liste provisoire des candidats pour les \u00e9lections de la cours constitutionnelle\u00a0 du 07.12.2024. voir ici Listes des candidats","og_url":"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/","og_site_name":"Facult\u00e9 De Droit Et Des Sciences Politiques","article_published_time":"2024-11-10T09:47:39+00:00","article_modified_time":"2024-11-10T11:02:49+00:00","og_image":[{"width":510,"height":336,"url":"https:\/\/www.ummto.dz\/fdsp\/wp-content\/uploads\/2023\/10\/avis.webp","type":"image\/webp"}],"author":"FDSP","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"FDSP","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/#article","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/"},"author":{"name":"FDSP","@id":"https:\/\/www.ummto.dz\/fdsp\/#\/schema\/person\/a868b9830e33c4360cb22a4100c4c7e0"},"headline":"Liste Provisoire des Candidats pour les Elections de la Cours Constitutionnelle du 07.12.2024.","datePublished":"2024-11-10T09:47:39+00:00","dateModified":"2024-11-10T11:02:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/"},"wordCount":100,"image":{"@id":"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fdsp\/wp-content\/uploads\/2023\/10\/avis.webp","articleSection":["Actualit\u00e9","dep droit","dep-politique"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/","url":"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/","name":"Liste Provisoire des Candidats pour les Elections de la Cours Constitutionnelle du 07.12.2024. - Facult\u00e9 De Droit Et Des Sciences Politiques","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fdsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fdsp\/wp-content\/uploads\/2023\/10\/avis.webp","datePublished":"2024-11-10T09:47:39+00:00","dateModified":"2024-11-10T11:02:49+00:00","author":{"@id":"https:\/\/www.ummto.dz\/fdsp\/#\/schema\/person\/a868b9830e33c4360cb22a4100c4c7e0"},"breadcrumb":{"@id":"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/#primaryimage","url":"https:\/\/www.ummto.dz\/fdsp\/wp-content\/uploads\/2023\/10\/avis.webp","contentUrl":"https:\/\/www.ummto.dz\/fdsp\/wp-content\/uploads\/2023\/10\/avis.webp","width":510,"height":336},{"@type":"BreadcrumbList","@id":"https:\/\/www.ummto.dz\/fdsp\/liste-provisoire-des-candidats-pour-les-elections-de-la-cours-constitutionnelle-du-07-12-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ummto.dz\/fdsp\/"},{"@type":"ListItem","position":2,"name":"Liste Provisoire des Candidats pour les Elections de la Cours Constitutionnelle du 07.12.2024."}]},{"@type":"WebSite","@id":"https:\/\/www.ummto.dz\/fdsp\/#website","url":"https:\/\/www.ummto.dz\/fdsp\/","name":"Facult\u00e9 De Droit Et Des Sciences Politiques","description":"Facult\u00e9 de Droit","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ummto.dz\/fdsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ummto.dz\/fdsp\/#\/schema\/person\/a868b9830e33c4360cb22a4100c4c7e0","name":"FDSP","url":"https:\/\/www.ummto.dz\/fdsp\/author\/fdsp\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ummto.dz\/fdsp\/wp-json\/wp\/v2\/posts\/5593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ummto.dz\/fdsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ummto.dz\/fdsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fdsp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fdsp\/wp-json\/wp\/v2\/comments?post=5593"}],"version-history":[{"count":3,"href":"https:\/\/www.ummto.dz\/fdsp\/wp-json\/wp\/v2\/posts\/5593\/revisions"}],"predecessor-version":[{"id":5598,"href":"https:\/\/www.ummto.dz\/fdsp\/wp-json\/wp\/v2\/posts\/5593\/revisions\/5598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fdsp\/wp-json\/wp\/v2\/media\/5049"}],"wp:attachment":[{"href":"https:\/\/www.ummto.dz\/fdsp\/wp-json\/wp\/v2\/media?parent=5593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ummto.dz\/fdsp\/wp-json\/wp\/v2\/categories?post=5593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ummto.dz\/fdsp\/wp-json\/wp\/v2\/tags?post=5593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}