{"id":8208,"date":"2024-09-16T14:17:45","date_gmt":"2024-09-16T13:17:45","guid":{"rendered":"https:\/\/www.ummto.dz\/fgei\/?p=8208"},"modified":"2024-09-16T21:13:14","modified_gmt":"2024-09-16T20:13:14","slug":"planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes","status":"publish","type":"post","link":"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/","title":{"rendered":"Planning des examens dettes L2\/M1 et la listes des \u00e9tudiants concern\u00e9s"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<div class=\"gmail_default\"><strong><span style=\"color: #000000\">Les \u00e9tudiants L3 et M2 admis avec dettes, sont invit\u00e9s \u00e0 consulter le planning des examens dettes, dont le hyperlien est sur le planning p\u00e9dagogique:<\/span><\/strong><\/div>\n<div class=\"gmail_default\"><\/div>\n<div class=\"gmail_default\" style=\"text-align: center\"><strong><span style=\"font-size: large;color: #000080\">\u00a0&gt;&gt;<a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/e\/2PACX-1vSAZ14i9NLzrOMnnGbxZ0YfiZ27U3Si-AUlPH854BvbTEBNBZdgqyp9sc4D7Bz0sEzqUt-DyC2ZK3lS\/pubhtml\" target=\"_blank\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/docs.google.com\/spreadsheets\/d\/e\/2PACX-1vSAZ14i9NLzrOMnnGbxZ0YfiZ27U3Si-AUlPH854BvbTEBNBZdgqyp9sc4D7Bz0sEzqUt-DyC2ZK3lS\/pubhtml&amp;source=gmail&amp;ust=1726578399794000&amp;usg=AOvVaw2S-dVbE73_BZirB2J75wuc\" rel=\"noopener\" style=\"color: #000080\">Planning des examens dettes L2\/M1 et la listes des \u00e9tudiants concern\u00e9s<\/a>&lt;&lt;<\/span><\/strong><\/div>\n<div class=\"gmail_default\" style=\"text-align: center\"><strong><span style=\"font-size: large;color: #000080\"><\/span><\/strong><\/div>\n<div class=\"gmail_default\" style=\"text-align: left\"><span style=\"color: #ff0000\"><strong><span style=\"font-size: large\"><span style=\"text-decoration: underline\">NB :<\/span> <span style=\"color: #800000\">Seule la note de l&rsquo;examen sera prise en compte dans la note finale de la mati\u00e8re en dette.<\/span><\/span><\/strong><\/span><\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00e9tudiants L3 et M2 admis avec dettes, sont invit\u00e9s \u00e0 consulter le planning des examens dettes, dont le hyperlien est sur le planning p\u00e9dagogique: \u00a0&gt;&gt;Planning des examens dettes L2\/M1 et la listes des \u00e9tudiants concern\u00e9s&lt;&lt; NB : Seule la note de l&rsquo;examen sera prise en compte dans la note finale de la mati\u00e8re en [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":8209,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[7,15],"tags":[],"class_list":["post-8208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-new-dep-informatique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Planning des examens dettes L2\/M1 et la listes des \u00e9tudiants concern\u00e9s - Facult\u00e9 du G\u00e9nie Electrique et d&#039;Informatique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Planning des examens dettes L2\/M1 et la listes des \u00e9tudiants concern\u00e9s - Facult\u00e9 du G\u00e9nie Electrique et d&#039;Informatique\" \/>\n<meta property=\"og:description\" content=\"Les \u00e9tudiants L3 et M2 admis avec dettes, sont invit\u00e9s \u00e0 consulter le planning des examens dettes, dont le hyperlien est sur le planning p\u00e9dagogique: \u00a0&gt;&gt;Planning des examens dettes L2\/M1 et la listes des \u00e9tudiants concern\u00e9s&lt;&lt; NB : Seule la note de l&#039;examen sera prise en compte dans la note finale de la mati\u00e8re en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/\" \/>\n<meta property=\"og:site_name\" content=\"Facult\u00e9 du G\u00e9nie Electrique et d&#039;Informatique\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-16T13:17:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-16T20:13:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ummto.dz\/fgei\/wp-content\/uploads\/2024\/09\/telechargement-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"162\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"eivalc eivalc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"eivalc eivalc\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\\\/\"},\"author\":{\"name\":\"eivalc eivalc\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/#\\\/schema\\\/person\\\/55d2af4c5bcd4e930baba1ecfc47f46e\"},\"headline\":\"Planning des examens dettes L2\\\/M1 et la listes des \u00e9tudiants concern\u00e9s\",\"datePublished\":\"2024-09-16T13:17:45+00:00\",\"dateModified\":\"2024-09-16T20:13:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\\\/\"},\"wordCount\":140,\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/telechargement-.jpg\",\"articleSection\":[\"Actualit\u00e9\",\"Informatique\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\\\/\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\\\/\",\"name\":\"Planning des examens dettes L2\\\/M1 et la listes des \u00e9tudiants concern\u00e9s - Facult\u00e9 du G\u00e9nie Electrique et d&#039;Informatique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/telechargement-.jpg\",\"datePublished\":\"2024-09-16T13:17:45+00:00\",\"dateModified\":\"2024-09-16T20:13:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/#\\\/schema\\\/person\\\/55d2af4c5bcd4e930baba1ecfc47f46e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/telechargement-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/telechargement-.jpg\",\"width\":300,\"height\":162},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Planning des examens dettes L2\\\/M1 et la listes des \u00e9tudiants concern\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/#website\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/\",\"name\":\"Facult\u00e9 du G\u00e9nie Electrique et d&#039;Informatique\",\"description\":\"UMMTO\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/#\\\/schema\\\/person\\\/55d2af4c5bcd4e930baba1ecfc47f46e\",\"name\":\"eivalc eivalc\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fgei\\\/author\\\/eivalc2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Planning des examens dettes L2\/M1 et la listes des \u00e9tudiants concern\u00e9s - Facult\u00e9 du G\u00e9nie Electrique et d&#039;Informatique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/","og_locale":"fr_FR","og_type":"article","og_title":"Planning des examens dettes L2\/M1 et la listes des \u00e9tudiants concern\u00e9s - Facult\u00e9 du G\u00e9nie Electrique et d&#039;Informatique","og_description":"Les \u00e9tudiants L3 et M2 admis avec dettes, sont invit\u00e9s \u00e0 consulter le planning des examens dettes, dont le hyperlien est sur le planning p\u00e9dagogique: \u00a0&gt;&gt;Planning des examens dettes L2\/M1 et la listes des \u00e9tudiants concern\u00e9s&lt;&lt; NB : Seule la note de l'examen sera prise en compte dans la note finale de la mati\u00e8re en [&hellip;]","og_url":"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/","og_site_name":"Facult\u00e9 du G\u00e9nie Electrique et d&#039;Informatique","article_published_time":"2024-09-16T13:17:45+00:00","article_modified_time":"2024-09-16T20:13:14+00:00","og_image":[{"width":300,"height":162,"url":"https:\/\/www.ummto.dz\/fgei\/wp-content\/uploads\/2024\/09\/telechargement-.jpg","type":"image\/jpeg"}],"author":"eivalc eivalc","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"eivalc eivalc","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/#article","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/"},"author":{"name":"eivalc eivalc","@id":"https:\/\/www.ummto.dz\/fgei\/#\/schema\/person\/55d2af4c5bcd4e930baba1ecfc47f46e"},"headline":"Planning des examens dettes L2\/M1 et la listes des \u00e9tudiants concern\u00e9s","datePublished":"2024-09-16T13:17:45+00:00","dateModified":"2024-09-16T20:13:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/"},"wordCount":140,"image":{"@id":"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fgei\/wp-content\/uploads\/2024\/09\/telechargement-.jpg","articleSection":["Actualit\u00e9","Informatique"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/","url":"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/","name":"Planning des examens dettes L2\/M1 et la listes des \u00e9tudiants concern\u00e9s - Facult\u00e9 du G\u00e9nie Electrique et d&#039;Informatique","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fgei\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/#primaryimage"},"image":{"@id":"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fgei\/wp-content\/uploads\/2024\/09\/telechargement-.jpg","datePublished":"2024-09-16T13:17:45+00:00","dateModified":"2024-09-16T20:13:14+00:00","author":{"@id":"https:\/\/www.ummto.dz\/fgei\/#\/schema\/person\/55d2af4c5bcd4e930baba1ecfc47f46e"},"breadcrumb":{"@id":"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/#primaryimage","url":"https:\/\/www.ummto.dz\/fgei\/wp-content\/uploads\/2024\/09\/telechargement-.jpg","contentUrl":"https:\/\/www.ummto.dz\/fgei\/wp-content\/uploads\/2024\/09\/telechargement-.jpg","width":300,"height":162},{"@type":"BreadcrumbList","@id":"https:\/\/www.ummto.dz\/fgei\/planning-des-examens-dettes-l2-m1-et-la-listes-des-etudiants-concernes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ummto.dz\/fgei\/"},{"@type":"ListItem","position":2,"name":"Planning des examens dettes L2\/M1 et la listes des \u00e9tudiants concern\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.ummto.dz\/fgei\/#website","url":"https:\/\/www.ummto.dz\/fgei\/","name":"Facult\u00e9 du G\u00e9nie Electrique et d&#039;Informatique","description":"UMMTO","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ummto.dz\/fgei\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ummto.dz\/fgei\/#\/schema\/person\/55d2af4c5bcd4e930baba1ecfc47f46e","name":"eivalc eivalc","url":"https:\/\/www.ummto.dz\/fgei\/author\/eivalc2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ummto.dz\/fgei\/wp-json\/wp\/v2\/posts\/8208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ummto.dz\/fgei\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ummto.dz\/fgei\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fgei\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fgei\/wp-json\/wp\/v2\/comments?post=8208"}],"version-history":[{"count":5,"href":"https:\/\/www.ummto.dz\/fgei\/wp-json\/wp\/v2\/posts\/8208\/revisions"}],"predecessor-version":[{"id":8216,"href":"https:\/\/www.ummto.dz\/fgei\/wp-json\/wp\/v2\/posts\/8208\/revisions\/8216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fgei\/wp-json\/wp\/v2\/media\/8209"}],"wp:attachment":[{"href":"https:\/\/www.ummto.dz\/fgei\/wp-json\/wp\/v2\/media?parent=8208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ummto.dz\/fgei\/wp-json\/wp\/v2\/categories?post=8208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ummto.dz\/fgei\/wp-json\/wp\/v2\/tags?post=8208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}