{"id":6798,"date":"2025-11-26T14:45:20","date_gmt":"2025-11-26T13:45:20","guid":{"rendered":"https:\/\/www.ummto.dz\/fll\/?p=6798"},"modified":"2025-11-26T14:49:47","modified_gmt":"2025-11-26T13:49:47","slug":"avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki","status":"publish","type":"post","link":"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/","title":{"rendered":"Avis de soutenance de th\u00e8se de doctorat LMD de Monsieur IKHERBANE Arezki"},"content":{"rendered":"\n[et_pb_section fb_built=\u00a0\u00bb1&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb type=\u00a0\u00bb4_4&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.ummto.dz\/fll\/wp-content\/uploads\/2025\/11\/Numeriser3-2-scaled.jpg\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb show_in_lightbox=\u00a0\u00bbon\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":2969,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[7,11],"tags":[],"class_list":["post-6798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-news_amazigh"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avis de soutenance de th\u00e8se de doctorat LMD de Monsieur IKHERBANE Arezki - Facult\u00e9 des Lettres et des Langues<\/title>\n<meta name=\"description\" content=\"Avis de soutenance de th\u00e8se de doctorat LMD de Mr IKHERBANE Arezki\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avis de soutenance de th\u00e8se de doctorat LMD de Monsieur IKHERBANE Arezki - Facult\u00e9 des Lettres et des Langues\" \/>\n<meta property=\"og:description\" content=\"Avis de soutenance de th\u00e8se de doctorat LMD de Mr IKHERBANE Arezki\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/\" \/>\n<meta property=\"og:site_name\" content=\"Facult\u00e9 des Lettres et des Langues\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-26T13:45:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T13:49:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ummto.dz\/fll\/wp-content\/uploads\/2021\/11\/Soutenance.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"FLL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"FLL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\\\/\"},\"author\":{\"name\":\"FLL\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/#\\\/schema\\\/person\\\/d03e7460fb5662f3475fff66fa1c5dc8\"},\"headline\":\"Avis de soutenance de th\u00e8se de doctorat LMD de Monsieur IKHERBANE Arezki\",\"datePublished\":\"2025-11-26T13:45:20+00:00\",\"dateModified\":\"2025-11-26T13:49:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\\\/\"},\"wordCount\":100,\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Soutenance.webp\",\"articleSection\":[\"Actualit\u00e9\",\"amazigh\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\\\/\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\\\/\",\"name\":\"Avis de soutenance de th\u00e8se de doctorat LMD de Monsieur IKHERBANE Arezki - Facult\u00e9 des Lettres et des Langues\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Soutenance.webp\",\"datePublished\":\"2025-11-26T13:45:20+00:00\",\"dateModified\":\"2025-11-26T13:49:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/#\\\/schema\\\/person\\\/d03e7460fb5662f3475fff66fa1c5dc8\"},\"description\":\"Avis de soutenance de th\u00e8se de doctorat LMD de Mr IKHERBANE Arezki\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Soutenance.webp\",\"contentUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Soutenance.webp\",\"width\":250,\"height\":250,\"caption\":\"Soutenance\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avis de soutenance de th\u00e8se de doctorat LMD de Monsieur IKHERBANE Arezki\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/#website\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/\",\"name\":\"Facult\u00e9 des Lettres et des Langues\",\"description\":\"Facult\u00e9 des Lettres et des Langues\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/#\\\/schema\\\/person\\\/d03e7460fb5662f3475fff66fa1c5dc8\",\"name\":\"FLL\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fll\\\/author\\\/fll\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avis de soutenance de th\u00e8se de doctorat LMD de Monsieur IKHERBANE Arezki - Facult\u00e9 des Lettres et des Langues","description":"Avis de soutenance de th\u00e8se de doctorat LMD de Mr IKHERBANE Arezki","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/","og_locale":"fr_FR","og_type":"article","og_title":"Avis de soutenance de th\u00e8se de doctorat LMD de Monsieur IKHERBANE Arezki - Facult\u00e9 des Lettres et des Langues","og_description":"Avis de soutenance de th\u00e8se de doctorat LMD de Mr IKHERBANE Arezki","og_url":"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/","og_site_name":"Facult\u00e9 des Lettres et des Langues","article_published_time":"2025-11-26T13:45:20+00:00","article_modified_time":"2025-11-26T13:49:47+00:00","og_image":[{"width":250,"height":250,"url":"https:\/\/www.ummto.dz\/fll\/wp-content\/uploads\/2021\/11\/Soutenance.webp","type":"image\/webp"}],"author":"FLL","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"FLL","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/#article","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/"},"author":{"name":"FLL","@id":"https:\/\/www.ummto.dz\/fll\/#\/schema\/person\/d03e7460fb5662f3475fff66fa1c5dc8"},"headline":"Avis de soutenance de th\u00e8se de doctorat LMD de Monsieur IKHERBANE Arezki","datePublished":"2025-11-26T13:45:20+00:00","dateModified":"2025-11-26T13:49:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/"},"wordCount":100,"image":{"@id":"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fll\/wp-content\/uploads\/2021\/11\/Soutenance.webp","articleSection":["Actualit\u00e9","amazigh"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/","url":"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/","name":"Avis de soutenance de th\u00e8se de doctorat LMD de Monsieur IKHERBANE Arezki - Facult\u00e9 des Lettres et des Langues","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fll\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/#primaryimage"},"image":{"@id":"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fll\/wp-content\/uploads\/2021\/11\/Soutenance.webp","datePublished":"2025-11-26T13:45:20+00:00","dateModified":"2025-11-26T13:49:47+00:00","author":{"@id":"https:\/\/www.ummto.dz\/fll\/#\/schema\/person\/d03e7460fb5662f3475fff66fa1c5dc8"},"description":"Avis de soutenance de th\u00e8se de doctorat LMD de Mr IKHERBANE Arezki","breadcrumb":{"@id":"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/#primaryimage","url":"https:\/\/www.ummto.dz\/fll\/wp-content\/uploads\/2021\/11\/Soutenance.webp","contentUrl":"https:\/\/www.ummto.dz\/fll\/wp-content\/uploads\/2021\/11\/Soutenance.webp","width":250,"height":250,"caption":"Soutenance"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ummto.dz\/fll\/avis-de-soutenance-de-these-de-doctorat-lmd-de-mr-ikherbane-arezki\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ummto.dz\/fll\/"},{"@type":"ListItem","position":2,"name":"Avis de soutenance de th\u00e8se de doctorat LMD de Monsieur IKHERBANE Arezki"}]},{"@type":"WebSite","@id":"https:\/\/www.ummto.dz\/fll\/#website","url":"https:\/\/www.ummto.dz\/fll\/","name":"Facult\u00e9 des Lettres et des Langues","description":"Facult\u00e9 des Lettres et des Langues","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ummto.dz\/fll\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ummto.dz\/fll\/#\/schema\/person\/d03e7460fb5662f3475fff66fa1c5dc8","name":"FLL","url":"https:\/\/www.ummto.dz\/fll\/author\/fll\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ummto.dz\/fll\/wp-json\/wp\/v2\/posts\/6798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ummto.dz\/fll\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ummto.dz\/fll\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fll\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fll\/wp-json\/wp\/v2\/comments?post=6798"}],"version-history":[{"count":3,"href":"https:\/\/www.ummto.dz\/fll\/wp-json\/wp\/v2\/posts\/6798\/revisions"}],"predecessor-version":[{"id":6804,"href":"https:\/\/www.ummto.dz\/fll\/wp-json\/wp\/v2\/posts\/6798\/revisions\/6804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fll\/wp-json\/wp\/v2\/media\/2969"}],"wp:attachment":[{"href":"https:\/\/www.ummto.dz\/fll\/wp-json\/wp\/v2\/media?parent=6798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ummto.dz\/fll\/wp-json\/wp\/v2\/categories?post=6798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ummto.dz\/fll\/wp-json\/wp\/v2\/tags?post=6798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}