{"id":69581,"date":"2022-12-05T21:48:18","date_gmt":"2022-12-05T20:48:18","guid":{"rendered":"https:\/\/www.ummto.dz\/fsecsg\/?p=69581"},"modified":"2022-12-05T21:49:54","modified_gmt":"2022-12-05T20:49:54","slug":"emploi-de-temps-master-1-et-master2-grh-2022-2023","status":"publish","type":"post","link":"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/","title":{"rendered":"Emploi de temps Master 1 et Master2 \/GRH\/2022-2023"},"content":{"rendered":"[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbText\u00a0\u00bb _builder_version=\u00a0\u00bb4.19.1&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<p><a href=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/Emplois-du-temps-Master1-et-Master2-GRH.docx\" rel=\"attachment wp-att-69584\">\u00a0-Emplois du temps Master1 et Master2 GRH<\/a><\/p>\n<p><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]","protected":false},"excerpt":{"rendered":"<p>\u00a0-Emplois du temps Master1 et Master2 GRH<\/p>\n","protected":false},"author":4,"featured_media":69462,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"categories":[36,24],"tags":[],"class_list":["post-69581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emploi-sc-gestion","category-new-dep-sc-gestion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emploi de temps Master 1 et Master2 \/GRH\/2022-2023 - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emploi de temps Master 1 et Master2 \/GRH\/2022-2023 - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"og:description\" content=\"\u00a0-Emplois du temps Master1 et Master2 GRH\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-05T20:48:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-05T20:49:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/emploi-de-temp-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"286\" \/>\n\t<meta property=\"og:image:height\" content=\"176\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FSECSG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"FSECSG\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/emploi-de-temps-master-1-et-master2-grh-2022-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/emploi-de-temps-master-1-et-master2-grh-2022-2023\\\/\"},\"author\":{\"name\":\"FSECSG\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"headline\":\"Emploi de temps Master 1 et Master2 \\\/GRH\\\/2022-2023\",\"datePublished\":\"2022-12-05T20:48:18+00:00\",\"dateModified\":\"2022-12-05T20:49:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/emploi-de-temps-master-1-et-master2-grh-2022-2023\\\/\"},\"wordCount\":100,\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/emploi-de-temps-master-1-et-master2-grh-2022-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/emploi-de-temp-1.jpg\",\"articleSection\":[\"emploi Sc gestion\",\"Sc gestion\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/emploi-de-temps-master-1-et-master2-grh-2022-2023\\\/\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/emploi-de-temps-master-1-et-master2-grh-2022-2023\\\/\",\"name\":\"Emploi de temps Master 1 et Master2 \\\/GRH\\\/2022-2023 - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/emploi-de-temps-master-1-et-master2-grh-2022-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/emploi-de-temps-master-1-et-master2-grh-2022-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/emploi-de-temp-1.jpg\",\"datePublished\":\"2022-12-05T20:48:18+00:00\",\"dateModified\":\"2022-12-05T20:49:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/emploi-de-temps-master-1-et-master2-grh-2022-2023\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/emploi-de-temps-master-1-et-master2-grh-2022-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/emploi-de-temps-master-1-et-master2-grh-2022-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/emploi-de-temp-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/emploi-de-temp-1.jpg\",\"width\":286,\"height\":176},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/emploi-de-temps-master-1-et-master2-grh-2022-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emploi de temps Master 1 et Master2 \\\/GRH\\\/2022-2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\",\"name\":\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"description\":\"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\",\"name\":\"FSECSG\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/author\\\/fsecsg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emploi de temps Master 1 et Master2 \/GRH\/2022-2023 - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"Emploi de temps Master 1 et Master2 \/GRH\/2022-2023 - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","og_description":"\u00a0-Emplois du temps Master1 et Master2 GRH","og_url":"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/","og_site_name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","article_published_time":"2022-12-05T20:48:18+00:00","article_modified_time":"2022-12-05T20:49:54+00:00","og_image":[{"width":286,"height":176,"url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/emploi-de-temp-1.jpg","type":"image\/jpeg"}],"author":"FSECSG","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"FSECSG"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/#article","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/"},"author":{"name":"FSECSG","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"headline":"Emploi de temps Master 1 et Master2 \/GRH\/2022-2023","datePublished":"2022-12-05T20:48:18+00:00","dateModified":"2022-12-05T20:49:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/"},"wordCount":100,"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/emploi-de-temp-1.jpg","articleSection":["emploi Sc gestion","Sc gestion"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/","url":"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/","name":"Emploi de temps Master 1 et Master2 \/GRH\/2022-2023 - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/emploi-de-temp-1.jpg","datePublished":"2022-12-05T20:48:18+00:00","dateModified":"2022-12-05T20:49:54+00:00","author":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"breadcrumb":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/#primaryimage","url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/emploi-de-temp-1.jpg","contentUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/emploi-de-temp-1.jpg","width":286,"height":176},{"@type":"BreadcrumbList","@id":"https:\/\/www.ummto.dz\/fsecsg\/emploi-de-temps-master-1-et-master2-grh-2022-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ummto.dz\/fsecsg\/"},{"@type":"ListItem","position":2,"name":"Emploi de temps Master 1 et Master2 \/GRH\/2022-2023"}]},{"@type":"WebSite","@id":"https:\/\/www.ummto.dz\/fsecsg\/#website","url":"https:\/\/www.ummto.dz\/fsecsg\/","name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","description":"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ummto.dz\/fsecsg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3","name":"FSECSG","url":"https:\/\/www.ummto.dz\/fsecsg\/author\/fsecsg\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/69581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/comments?post=69581"}],"version-history":[{"count":3,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/69581\/revisions"}],"predecessor-version":[{"id":69585,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/69581\/revisions\/69585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media\/69462"}],"wp:attachment":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media?parent=69581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/categories?post=69581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/tags?post=69581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}