{"id":90468,"date":"2025-05-05T14:05:37","date_gmt":"2025-05-05T12:05:37","guid":{"rendered":"https:\/\/www.ummto.dz\/fsecsg\/?p=90468"},"modified":"2025-05-05T14:09:09","modified_gmt":"2025-05-05T12:09:09","slug":"lien-pour-la-fiche-de-voeux-l1-vers-l2","status":"publish","type":"post","link":"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/","title":{"rendered":"Lien pour la fiche de v\u0153ux L1 vers L2."},"content":{"rendered":"[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbText\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb min_height=\u00a0\u00bb187px\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<p><strong><span>Merci de bien vouloir remplir la fiche en ligne disponible via le lien ci-dessous:<\/span><\/strong><\/p>\n<p><strong><span>Fiche de voeux L1 vers L2: <\/span><a href=\"https:\/\/forms.gle\/xisndD5iRa41V1GV8\" target=\"_blank\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/forms.gle\/xisndD5iRa41V1GV8&amp;source=gmail&amp;ust=1746532233616000&amp;usg=AOvVaw3YRSNps_tIlX9YbYdG9BZm\" rel=\"noopener\">https:\/\/forms.gle\/xisndD5iRa41V1GV8<\/a><\/strong><\/p>\n<p><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]","protected":false},"excerpt":{"rendered":"<p>Merci de bien vouloir remplir la fiche en ligne disponible via le lien ci-dessous: Fiche de voeux L1 vers L2: https:\/\/forms.gle\/xisndD5iRa41V1GV8<\/p>\n","protected":false},"author":4,"featured_media":88388,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"categories":[15,23,20,22,24],"tags":[],"class_list":["post-90468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-new-dep-sc-commerciale","category-new-dep-sceco","category-new-dep-sc-financiere","category-new-dep-sc-gestion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lien pour la fiche de v\u0153ux L1 vers L2. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lien pour la fiche de v\u0153ux L1 vers L2. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"og:description\" content=\"Merci de bien vouloir remplir la fiche en ligne disponible via le lien ci-dessous: Fiche de voeux L1 vers L2: https:\/\/forms.gle\/xisndD5iRa41V1GV8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/\" \/>\n<meta property=\"og:site_name\" content=\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-05T12:05:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-05T12:09:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2024\/11\/Important.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"FSECSG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"FSECSG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/lien-pour-la-fiche-de-voeux-l1-vers-l2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/lien-pour-la-fiche-de-voeux-l1-vers-l2\\\/\"},\"author\":{\"name\":\"FSECSG\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"headline\":\"Lien pour la fiche de v\u0153ux L1 vers L2.\",\"datePublished\":\"2025-05-05T12:05:37+00:00\",\"dateModified\":\"2025-05-05T12:09:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/lien-pour-la-fiche-de-voeux-l1-vers-l2\\\/\"},\"wordCount\":126,\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/lien-pour-la-fiche-de-voeux-l1-vers-l2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Important.webp\",\"articleSection\":[\"Actualit\u00e9\",\"Sc commerciale\",\"Sc Eco\",\"Sc financi\u00e8re hasnaoua\",\"Sc gestion\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/lien-pour-la-fiche-de-voeux-l1-vers-l2\\\/\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/lien-pour-la-fiche-de-voeux-l1-vers-l2\\\/\",\"name\":\"Lien pour la fiche de v\u0153ux L1 vers L2. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/lien-pour-la-fiche-de-voeux-l1-vers-l2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/lien-pour-la-fiche-de-voeux-l1-vers-l2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Important.webp\",\"datePublished\":\"2025-05-05T12:05:37+00:00\",\"dateModified\":\"2025-05-05T12:09:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/lien-pour-la-fiche-de-voeux-l1-vers-l2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/lien-pour-la-fiche-de-voeux-l1-vers-l2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/lien-pour-la-fiche-de-voeux-l1-vers-l2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Important.webp\",\"contentUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Important.webp\",\"width\":250,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/lien-pour-la-fiche-de-voeux-l1-vers-l2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lien pour la fiche de v\u0153ux L1 vers L2.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\",\"name\":\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"description\":\"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\",\"name\":\"FSECSG\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/author\\\/fsecsg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lien pour la fiche de v\u0153ux L1 vers L2. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/","og_locale":"fr_FR","og_type":"article","og_title":"Lien pour la fiche de v\u0153ux L1 vers L2. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","og_description":"Merci de bien vouloir remplir la fiche en ligne disponible via le lien ci-dessous: Fiche de voeux L1 vers L2: https:\/\/forms.gle\/xisndD5iRa41V1GV8","og_url":"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/","og_site_name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","article_published_time":"2025-05-05T12:05:37+00:00","article_modified_time":"2025-05-05T12:09:09+00:00","og_image":[{"width":250,"height":250,"url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2024\/11\/Important.webp","type":"image\/webp"}],"author":"FSECSG","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"FSECSG","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/#article","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/"},"author":{"name":"FSECSG","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"headline":"Lien pour la fiche de v\u0153ux L1 vers L2.","datePublished":"2025-05-05T12:05:37+00:00","dateModified":"2025-05-05T12:09:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/"},"wordCount":126,"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2024\/11\/Important.webp","articleSection":["Actualit\u00e9","Sc commerciale","Sc Eco","Sc financi\u00e8re hasnaoua","Sc gestion"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/","url":"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/","name":"Lien pour la fiche de v\u0153ux L1 vers L2. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/#primaryimage"},"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2024\/11\/Important.webp","datePublished":"2025-05-05T12:05:37+00:00","dateModified":"2025-05-05T12:09:09+00:00","author":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"breadcrumb":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/#primaryimage","url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2024\/11\/Important.webp","contentUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2024\/11\/Important.webp","width":250,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/www.ummto.dz\/fsecsg\/lien-pour-la-fiche-de-voeux-l1-vers-l2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ummto.dz\/fsecsg\/"},{"@type":"ListItem","position":2,"name":"Lien pour la fiche de v\u0153ux L1 vers L2."}]},{"@type":"WebSite","@id":"https:\/\/www.ummto.dz\/fsecsg\/#website","url":"https:\/\/www.ummto.dz\/fsecsg\/","name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","description":"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ummto.dz\/fsecsg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3","name":"FSECSG","url":"https:\/\/www.ummto.dz\/fsecsg\/author\/fsecsg\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/90468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/comments?post=90468"}],"version-history":[{"count":3,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/90468\/revisions"}],"predecessor-version":[{"id":90471,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/90468\/revisions\/90471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media\/88388"}],"wp:attachment":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media?parent=90468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/categories?post=90468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/tags?post=90468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}