{"id":91456,"date":"2025-07-24T15:45:53","date_gmt":"2025-07-24T13:45:53","guid":{"rendered":"https:\/\/www.ummto.dz\/fsecsg\/?p=91456"},"modified":"2025-07-24T15:47:58","modified_gmt":"2025-07-24T13:47:58","slug":"resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion","status":"publish","type":"post","link":"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/","title":{"rendered":"R\u00e9sultats des orientations apr\u00e8s traitement des recours de d\u00e9partement Sciences de Gestion."},"content":{"rendered":"[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbText\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb min_height=\u00a0\u00bb201px\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<p>&nbsp;<\/p>\n<div>\n<div dir=\"auto\" style=\"text-align: center\"><span style=\"text-decoration: underline\"><strong>R\u00e9sultats des orientations apr\u00e8s traitement des recours<\/strong><\/span><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Veuillez trouver, via les liens ci-dessous, les r\u00e9sultats d\u00e9finitifs des orientations apr\u00e8s traitement des recours:<\/div>\n<\/div>\n<div>\n<div dir=\"auto\"><strong>&#8211; L2 VERS L3<\/strong><\/div>\n<div dir=\"auto\"><strong><a href=\"https:\/\/drive.google.com\/file\/d\/1Yiohi3ychhBJiaKadm27yzxppdULfUTN\/view?usp=drive_link&amp;fbclid=IwZXh0bgNhZW0CMTAAYnJpZBExMWZsUnFvYTVPczFuWWhCMAEer2aM4Y5r9eqHdmmCjBjjNmosSoCbLa7C0wO9kef3GS0_8J8fuExzbj7IHEQ_aem_TedrCxvN4UpVqXUw0S2jGQ\" rel=\"nofollow noopener noreferrer\" role=\"link\" target=\"_blank\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/drive.google.com\/file\/d\/1Yiohi3ychhBJiaKadm27yzxppdULfUTN\/view?usp%3Ddrive_link%26fbclid%3DIwZXh0bgNhZW0CMTAAYnJpZBExMWZsUnFvYTVPczFuWWhCMAEer2aM4Y5r9eqHdmmCjBjjNmosSoCbLa7C0wO9kef3GS0_8J8fuExzbj7IHEQ_aem_TedrCxvN4UpVqXUw0S2jGQ&amp;source=gmail&amp;ust=1753448909206000&amp;usg=AOvVaw2-fSrpc8AvGiY_DmkgPPX5\">https:\/\/drive.google.com\/&#8230;\/1Yiohi3ychhBJiaKadm2&#8230;\/view&#8230;<\/a><\/strong><\/div>\n<\/div>\n<div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><strong>&#8211; L3 VERS MASTER<\/strong><\/div>\n<div dir=\"auto\"><strong><a href=\"https:\/\/drive.google.com\/file\/d\/1pu-VhkqPGp7lJ1TtLfP1GSRFax9-7Owx\/view?usp=sharing&amp;fbclid=IwZXh0bgNhZW0CMTAAYnJpZBExMWZsUnFvYTVPczFuWWhCMAEe0K8eAp2lDS77UBQpDvd8HA0KiyZutuYi56YDjJKSGwksYCuX76-RJaP7dV0_aem_HCKJ4nrUHsbMlsJV4GnHEA\" rel=\"nofollow noopener noreferrer\" role=\"link\" target=\"_blank\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/drive.google.com\/file\/d\/1pu-VhkqPGp7lJ1TtLfP1GSRFax9-7Owx\/view?usp%3Dsharing%26fbclid%3DIwZXh0bgNhZW0CMTAAYnJpZBExMWZsUnFvYTVPczFuWWhCMAEe0K8eAp2lDS77UBQpDvd8HA0KiyZutuYi56YDjJKSGwksYCuX76-RJaP7dV0_aem_HCKJ4nrUHsbMlsJV4GnHEA&amp;source=gmail&amp;ust=1753448909206000&amp;usg=AOvVaw3JQ5f6cM7QmWAYCMFPyyyT\">https:\/\/drive.google.com\/&#8230;\/1pu&#8230;\/view&#8230;<\/a><\/strong><\/div>\n<\/div>\n<p><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]","protected":false},"excerpt":{"rendered":"<p>&nbsp; R\u00e9sultats des orientations apr\u00e8s traitement des recours Veuillez trouver, via les liens ci-dessous, les r\u00e9sultats d\u00e9finitifs des orientations apr\u00e8s traitement des recours: &#8211; L2 VERS L3 https:\/\/drive.google.com\/&#8230;\/1Yiohi3ychhBJiaKadm2&#8230;\/view&#8230; &#8211; L3 VERS MASTER https:\/\/drive.google.com\/&#8230;\/1pu&#8230;\/view&#8230;<\/p>\n","protected":false},"author":4,"featured_media":80767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"categories":[24],"tags":[],"class_list":["post-91456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-new-dep-sc-gestion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9sultats des orientations apr\u00e8s traitement des recours de d\u00e9partement Sciences de Gestion. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9sultats des orientations apr\u00e8s traitement des recours de d\u00e9partement Sciences de Gestion. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"og:description\" content=\"&nbsp; R\u00e9sultats des orientations apr\u00e8s traitement des recours Veuillez trouver, via les liens ci-dessous, les r\u00e9sultats d\u00e9finitifs des orientations apr\u00e8s traitement des recours: - L2 VERS L3 https:\/\/drive.google.com\/...\/1Yiohi3ychhBJiaKadm2...\/view... - L3 VERS MASTER https:\/\/drive.google.com\/...\/1pu...\/view...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/\" \/>\n<meta property=\"og:site_name\" content=\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-24T13:45:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-24T13:47:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2023\/09\/orient.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"180\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FSECSG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"FSECSG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\\\/\"},\"author\":{\"name\":\"FSECSG\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"headline\":\"R\u00e9sultats des orientations apr\u00e8s traitement des recours de d\u00e9partement Sciences de Gestion.\",\"datePublished\":\"2025-07-24T13:45:53+00:00\",\"dateModified\":\"2025-07-24T13:47:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\\\/\"},\"wordCount\":152,\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/orient.jpg\",\"articleSection\":[\"Sc gestion\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\\\/\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\\\/\",\"name\":\"R\u00e9sultats des orientations apr\u00e8s traitement des recours de d\u00e9partement Sciences de Gestion. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/orient.jpg\",\"datePublished\":\"2025-07-24T13:45:53+00:00\",\"dateModified\":\"2025-07-24T13:47:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/orient.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/orient.jpg\",\"width\":180,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9sultats des orientations apr\u00e8s traitement des recours de d\u00e9partement Sciences de Gestion.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\",\"name\":\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"description\":\"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\",\"name\":\"FSECSG\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/author\\\/fsecsg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9sultats des orientations apr\u00e8s traitement des recours de d\u00e9partement Sciences de Gestion. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9sultats des orientations apr\u00e8s traitement des recours de d\u00e9partement Sciences de Gestion. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","og_description":"&nbsp; R\u00e9sultats des orientations apr\u00e8s traitement des recours Veuillez trouver, via les liens ci-dessous, les r\u00e9sultats d\u00e9finitifs des orientations apr\u00e8s traitement des recours: - L2 VERS L3 https:\/\/drive.google.com\/...\/1Yiohi3ychhBJiaKadm2...\/view... - L3 VERS MASTER https:\/\/drive.google.com\/...\/1pu...\/view...","og_url":"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/","og_site_name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","article_published_time":"2025-07-24T13:45:53+00:00","article_modified_time":"2025-07-24T13:47:58+00:00","og_image":[{"width":180,"height":180,"url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2023\/09\/orient.jpg","type":"image\/jpeg"}],"author":"FSECSG","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"FSECSG","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/#article","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/"},"author":{"name":"FSECSG","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"headline":"R\u00e9sultats des orientations apr\u00e8s traitement des recours de d\u00e9partement Sciences de Gestion.","datePublished":"2025-07-24T13:45:53+00:00","dateModified":"2025-07-24T13:47:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/"},"wordCount":152,"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2023\/09\/orient.jpg","articleSection":["Sc gestion"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/","url":"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/","name":"R\u00e9sultats des orientations apr\u00e8s traitement des recours de d\u00e9partement Sciences de Gestion. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/#primaryimage"},"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2023\/09\/orient.jpg","datePublished":"2025-07-24T13:45:53+00:00","dateModified":"2025-07-24T13:47:58+00:00","author":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"breadcrumb":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/#primaryimage","url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2023\/09\/orient.jpg","contentUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2023\/09\/orient.jpg","width":180,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/www.ummto.dz\/fsecsg\/resultats-des-orientations-apres-traitement-des-recours-de-departement-sciences-de-gestion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ummto.dz\/fsecsg\/"},{"@type":"ListItem","position":2,"name":"R\u00e9sultats des orientations apr\u00e8s traitement des recours de d\u00e9partement Sciences de Gestion."}]},{"@type":"WebSite","@id":"https:\/\/www.ummto.dz\/fsecsg\/#website","url":"https:\/\/www.ummto.dz\/fsecsg\/","name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","description":"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ummto.dz\/fsecsg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3","name":"FSECSG","url":"https:\/\/www.ummto.dz\/fsecsg\/author\/fsecsg\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/91456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/comments?post=91456"}],"version-history":[{"count":3,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/91456\/revisions"}],"predecessor-version":[{"id":91459,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/91456\/revisions\/91459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media\/80767"}],"wp:attachment":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media?parent=91456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/categories?post=91456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/tags?post=91456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}