{"id":92578,"date":"2025-12-11T14:09:58","date_gmt":"2025-12-11T13:09:58","guid":{"rendered":"https:\/\/www.ummto.dz\/fsecsg\/?p=92578"},"modified":"2025-12-11T14:12:49","modified_gmt":"2025-12-11T13:12:49","slug":"avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38","status":"publish","type":"post","link":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/","title":{"rendered":"Avis aux \u00e9tudiants de L1, G2,\u00a0des groupes 33 et 38."},"content":{"rendered":"[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbText\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb min_height=\u00a0\u00bb218px\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<p style=\"text-align: center\"><strong><span style=\"text-decoration: underline;color: #ff0000\">Avis aux \u00e9tudiants de L1, G2,\u00a0des groupes 33 et 38\u00a0<\/span><\/strong><\/p>\n<div dir=\"auto\"><strong>Les TD de la statistique1, programm\u00e9s le jeudi, sont avanc\u00e9s au mercredi 17 d\u00e9cembre de 14h \u00e0 15h30m, \u00e0 l\u2019amphith\u00e9\u00e2tre BENYAHIA.<\/strong><\/div>\n<p><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]","protected":false},"excerpt":{"rendered":"<p>Avis aux \u00e9tudiants de L1, G2,\u00a0des groupes 33 et 38\u00a0 Les TD de la statistique1, programm\u00e9s le jeudi, sont avanc\u00e9s au mercredi 17 d\u00e9cembre de 14h \u00e0 15h30m, \u00e0 l\u2019amphith\u00e9\u00e2tre BENYAHIA.<\/p>\n","protected":false},"author":4,"featured_media":69459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"categories":[24],"tags":[],"class_list":["post-92578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-new-dep-sc-gestion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avis aux \u00e9tudiants de L1, G2,\u00a0des groupes 33 et 38. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avis aux \u00e9tudiants de L1, G2,\u00a0des groupes 33 et 38. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"og:description\" content=\"Avis aux \u00e9tudiants de L1, G2,\u00a0des groupes 33 et 38\u00a0 Les TD de la statistique1, programm\u00e9s le jeudi, sont avanc\u00e9s au mercredi 17 d\u00e9cembre de 14h \u00e0 15h30m, \u00e0 l\u2019amphith\u00e9\u00e2tre BENYAHIA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/\" \/>\n<meta property=\"og:site_name\" content=\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-11T13:09:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-11T13:12:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/infos-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FSECSG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"FSECSG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\\\/\"},\"author\":{\"name\":\"FSECSG\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"headline\":\"Avis aux \u00e9tudiants de L1, G2,\u00a0des groupes 33 et 38.\",\"datePublished\":\"2025-12-11T13:09:58+00:00\",\"dateModified\":\"2025-12-11T13:12:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\\\/\"},\"wordCount\":130,\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/infos-1.jpg\",\"articleSection\":[\"Sc gestion\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\\\/\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\\\/\",\"name\":\"Avis aux \u00e9tudiants de L1, G2,\u00a0des groupes 33 et 38. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/infos-1.jpg\",\"datePublished\":\"2025-12-11T13:09:58+00:00\",\"dateModified\":\"2025-12-11T13:12:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/infos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/infos-1.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avis aux \u00e9tudiants de L1, G2,\u00a0des groupes 33 et 38.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\",\"name\":\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"description\":\"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\",\"name\":\"FSECSG\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/author\\\/fsecsg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avis aux \u00e9tudiants de L1, G2,\u00a0des groupes 33 et 38. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/","og_locale":"fr_FR","og_type":"article","og_title":"Avis aux \u00e9tudiants de L1, G2,\u00a0des groupes 33 et 38. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","og_description":"Avis aux \u00e9tudiants de L1, G2,\u00a0des groupes 33 et 38\u00a0 Les TD de la statistique1, programm\u00e9s le jeudi, sont avanc\u00e9s au mercredi 17 d\u00e9cembre de 14h \u00e0 15h30m, \u00e0 l\u2019amphith\u00e9\u00e2tre BENYAHIA.","og_url":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/","og_site_name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","article_published_time":"2025-12-11T13:09:58+00:00","article_modified_time":"2025-12-11T13:12:49+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/infos-1.jpg","type":"image\/jpeg"}],"author":"FSECSG","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"FSECSG","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/#article","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/"},"author":{"name":"FSECSG","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"headline":"Avis aux \u00e9tudiants de L1, G2,\u00a0des groupes 33 et 38.","datePublished":"2025-12-11T13:09:58+00:00","dateModified":"2025-12-11T13:12:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/"},"wordCount":130,"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/infos-1.jpg","articleSection":["Sc gestion"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/","url":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/","name":"Avis aux \u00e9tudiants de L1, G2,\u00a0des groupes 33 et 38. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/#primaryimage"},"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/infos-1.jpg","datePublished":"2025-12-11T13:09:58+00:00","dateModified":"2025-12-11T13:12:49+00:00","author":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"breadcrumb":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/#primaryimage","url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/infos-1.jpg","contentUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/infos-1.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-de-l1-g2-des-groupes-33-et-38\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ummto.dz\/fsecsg\/"},{"@type":"ListItem","position":2,"name":"Avis aux \u00e9tudiants de L1, G2,\u00a0des groupes 33 et 38."}]},{"@type":"WebSite","@id":"https:\/\/www.ummto.dz\/fsecsg\/#website","url":"https:\/\/www.ummto.dz\/fsecsg\/","name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","description":"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ummto.dz\/fsecsg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3","name":"FSECSG","url":"https:\/\/www.ummto.dz\/fsecsg\/author\/fsecsg\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/92578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/comments?post=92578"}],"version-history":[{"count":3,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/92578\/revisions"}],"predecessor-version":[{"id":92581,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/92578\/revisions\/92581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media\/69459"}],"wp:attachment":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media?parent=92578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/categories?post=92578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/tags?post=92578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}