{"id":93030,"date":"2026-01-28T21:44:12","date_gmt":"2026-01-28T20:44:12","guid":{"rendered":"https:\/\/www.ummto.dz\/fsecsg\/?p=93030"},"modified":"2026-01-28T21:48:03","modified_gmt":"2026-01-28T20:48:03","slug":"avis-aux-etudiants-du-departement-4","status":"publish","type":"post","link":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/","title":{"rendered":"Avis aux \u00e9tudiants du d\u00e9partement."},"content":{"rendered":"[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbText\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<p>&nbsp;<\/p>\n<div>\n<div dir=\"auto\"><span style=\"text-decoration: underline\"><strong><span style=\"color: #ff0000;text-decoration: underline\">Report des examens de remplacement pr\u00e9vus demain<\/span><\/strong><\/span><\/div>\n<div dir=\"auto\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/div>\n<div dir=\"auto\">Nous informons les \u00e9tudiants du d\u00e9partement Sces de Gestion queles examens de remplacement pr\u00e9vus demain, jeudi 29 janvier 2026, sont report\u00e9s.<\/div>\n<div dir=\"auto\">Le planning mis \u00e0 jour:<span> \u21d2\u21d2 \u00a0\u00a0<\/span><strong><a href=\"http:\/\/urlz.fr\/v2pg?fbclid=IwZXh0bgNhZW0CMTAAYnJpZBExRjByTmdTZ0FSNjRIT2xqS3NydGMGYXBwX2lkEDIyMjAzOTE3ODgyMDA4OTIAAR5BUYUq3tBEdLRIfnn_Ok85OqIaSBJIDhZ_E18JVgrQBvWm9gxMQRTqw6w9TQ_aem_dsyHQyOQ4a7h_gkuXfqQbQ\" rel=\"nofollow noopener noreferrer\" role=\"link\" target=\"_blank\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/urlz.fr\/v2pg?fbclid%3DIwZXh0bgNhZW0CMTAAYnJpZBExRjByTmdTZ0FSNjRIT2xqS3NydGMGYXBwX2lkEDIyMjAzOTE3ODgyMDA4OTIAAR5BUYUq3tBEdLRIfnn_Ok85OqIaSBJIDhZ_E18JVgrQBvWm9gxMQRTqw6w9TQ_aem_dsyHQyOQ4a7h_gkuXfqQbQ&amp;source=gmail&amp;ust=1769718847847000&amp;usg=AOvVaw2rn9M3jgSKWLOSrKN50be0\">urlz.fr\/v2pg<\/a><\/strong><\/div>\n<\/div>\n<div>\n<div dir=\"auto\">Par ailleurs, les \u00e9tudiants ayant d\u00e9pos\u00e9 une justification d\u2019absence et n\u2019ayant pas pu passer leur examen de remplacement initialement pr\u00e9vu aujourd\u2019hui, mercredi 29 janvier 2026, pourront le composer dimanche 01 f\u00e9vrier 2026 selon l\u2019horaire indiqu\u00e9 dans le planning ci-dessus.<\/div>\n<div dir=\"auto\" style=\"text-align: center\"><span style=\"text-decoration: underline\"><em><strong>Le Chef de d\u00e9partement.<\/strong><\/em><\/span><\/div>\n<\/div>\n<p><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]","protected":false},"excerpt":{"rendered":"<p>&nbsp; Report des examens de remplacement pr\u00e9vus demain &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212; Nous informons les \u00e9tudiants du d\u00e9partement Sces de Gestion queles examens de remplacement pr\u00e9vus demain, jeudi 29 janvier 2026, sont report\u00e9s. Le planning mis \u00e0 jour: \u21d2\u21d2 \u00a0\u00a0urlz.fr\/v2pg Par ailleurs, les \u00e9tudiants ayant d\u00e9pos\u00e9 une justification d\u2019absence et n\u2019ayant pas pu passer leur examen de remplacement [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":88388,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"categories":[24],"tags":[],"class_list":["post-93030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-new-dep-sc-gestion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avis aux \u00e9tudiants du d\u00e9partement. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avis aux \u00e9tudiants du d\u00e9partement. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Report des examens de remplacement pr\u00e9vus demain --------------------- Nous informons les \u00e9tudiants du d\u00e9partement Sces de Gestion queles examens de remplacement pr\u00e9vus demain, jeudi 29 janvier 2026, sont report\u00e9s. Le planning mis \u00e0 jour: \u21d2\u21d2 \u00a0\u00a0urlz.fr\/v2pg Par ailleurs, les \u00e9tudiants ayant d\u00e9pos\u00e9 une justification d\u2019absence et n\u2019ayant pas pu passer leur examen de remplacement [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-28T20:44:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T20:48:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2024\/11\/Important.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"FSECSG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"FSECSG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-du-departement-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-du-departement-4\\\/\"},\"author\":{\"name\":\"FSECSG\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"headline\":\"Avis aux \u00e9tudiants du d\u00e9partement.\",\"datePublished\":\"2026-01-28T20:44:12+00:00\",\"dateModified\":\"2026-01-28T20:48:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-du-departement-4\\\/\"},\"wordCount\":179,\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-du-departement-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Important.webp\",\"articleSection\":[\"Sc gestion\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-du-departement-4\\\/\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-du-departement-4\\\/\",\"name\":\"Avis aux \u00e9tudiants du d\u00e9partement. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-du-departement-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-du-departement-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Important.webp\",\"datePublished\":\"2026-01-28T20:44:12+00:00\",\"dateModified\":\"2026-01-28T20:48:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-du-departement-4\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-du-departement-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-du-departement-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Important.webp\",\"contentUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Important.webp\",\"width\":250,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/avis-aux-etudiants-du-departement-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avis aux \u00e9tudiants du d\u00e9partement.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\",\"name\":\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"description\":\"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\",\"name\":\"FSECSG\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/author\\\/fsecsg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avis aux \u00e9tudiants du d\u00e9partement. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/","og_locale":"fr_FR","og_type":"article","og_title":"Avis aux \u00e9tudiants du d\u00e9partement. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","og_description":"&nbsp; Report des examens de remplacement pr\u00e9vus demain --------------------- Nous informons les \u00e9tudiants du d\u00e9partement Sces de Gestion queles examens de remplacement pr\u00e9vus demain, jeudi 29 janvier 2026, sont report\u00e9s. Le planning mis \u00e0 jour: \u21d2\u21d2 \u00a0\u00a0urlz.fr\/v2pg Par ailleurs, les \u00e9tudiants ayant d\u00e9pos\u00e9 une justification d\u2019absence et n\u2019ayant pas pu passer leur examen de remplacement [&hellip;]","og_url":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/","og_site_name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","article_published_time":"2026-01-28T20:44:12+00:00","article_modified_time":"2026-01-28T20:48:03+00:00","og_image":[{"width":250,"height":250,"url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2024\/11\/Important.webp","type":"image\/webp"}],"author":"FSECSG","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"FSECSG","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/#article","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/"},"author":{"name":"FSECSG","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"headline":"Avis aux \u00e9tudiants du d\u00e9partement.","datePublished":"2026-01-28T20:44:12+00:00","dateModified":"2026-01-28T20:48:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/"},"wordCount":179,"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2024\/11\/Important.webp","articleSection":["Sc gestion"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/","url":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/","name":"Avis aux \u00e9tudiants du d\u00e9partement. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/#primaryimage"},"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2024\/11\/Important.webp","datePublished":"2026-01-28T20:44:12+00:00","dateModified":"2026-01-28T20:48:03+00:00","author":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"breadcrumb":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/#primaryimage","url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2024\/11\/Important.webp","contentUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2024\/11\/Important.webp","width":250,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/www.ummto.dz\/fsecsg\/avis-aux-etudiants-du-departement-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ummto.dz\/fsecsg\/"},{"@type":"ListItem","position":2,"name":"Avis aux \u00e9tudiants du d\u00e9partement."}]},{"@type":"WebSite","@id":"https:\/\/www.ummto.dz\/fsecsg\/#website","url":"https:\/\/www.ummto.dz\/fsecsg\/","name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","description":"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ummto.dz\/fsecsg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3","name":"FSECSG","url":"https:\/\/www.ummto.dz\/fsecsg\/author\/fsecsg\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/93030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/comments?post=93030"}],"version-history":[{"count":3,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/93030\/revisions"}],"predecessor-version":[{"id":93033,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/93030\/revisions\/93033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media\/88388"}],"wp:attachment":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media?parent=93030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/categories?post=93030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/tags?post=93030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}