{"id":93709,"date":"2026-04-11T20:50:50","date_gmt":"2026-04-11T18:50:50","guid":{"rendered":"https:\/\/www.ummto.dz\/fsecsg\/?p=93709"},"modified":"2026-04-11T20:55:24","modified_gmt":"2026-04-11T18:55:24","slug":"information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30","status":"publish","type":"post","link":"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/","title":{"rendered":"Information pour les \u00e9tudiants de L1, groupes: 21\/22\/ 23\/24\/29\/30."},"content":{"rendered":"[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbText\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<p>&nbsp;<\/p>\n<div dir=\"auto\"><strong>Les \u00e9tudiants de premi\u00e8re ann\u00e9e LMD <span style=\"color: #ff0000\">groupe 21\/22\/23\/24\/29\/30<\/span> sont inform\u00e9s que l&rsquo;examen TD de statistiques 2 est programm\u00e9 dans les s\u00e9ances de TD <span style=\"color: #ff0000\">demain dimanche 12\/04\/2026 et <\/span><\/strong><span style=\"color: #ff0000\"><strong>\u00a0apr\u00e8s demain 13\/04\/2026.<\/strong><\/span><\/div>\n<p><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]","protected":false},"excerpt":{"rendered":"<p>&nbsp; Les \u00e9tudiants de premi\u00e8re ann\u00e9e LMD groupe 21\/22\/23\/24\/29\/30 sont inform\u00e9s que l&rsquo;examen TD de statistiques 2 est programm\u00e9 dans les s\u00e9ances de TD demain dimanche 12\/04\/2026 et \u00a0apr\u00e8s demain 13\/04\/2026.<\/p>\n","protected":false},"author":4,"featured_media":69459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"categories":[24],"tags":[],"class_list":["post-93709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-new-dep-sc-gestion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Information pour les \u00e9tudiants de L1, groupes: 21\/22\/ 23\/24\/29\/30. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Information pour les \u00e9tudiants de L1, groupes: 21\/22\/ 23\/24\/29\/30. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Les \u00e9tudiants de premi\u00e8re ann\u00e9e LMD groupe 21\/22\/23\/24\/29\/30 sont inform\u00e9s que l&#039;examen TD de statistiques 2 est programm\u00e9 dans les s\u00e9ances de TD demain dimanche 12\/04\/2026 et \u00a0apr\u00e8s demain 13\/04\/2026.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/\" \/>\n<meta property=\"og:site_name\" content=\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-11T18:50:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-11T18:55:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/infos-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FSECSG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"FSECSG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\\\/\"},\"author\":{\"name\":\"FSECSG\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"headline\":\"Information pour les \u00e9tudiants de L1, groupes: 21\\\/22\\\/ 23\\\/24\\\/29\\\/30.\",\"datePublished\":\"2026-04-11T18:50:50+00:00\",\"dateModified\":\"2026-04-11T18:55:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\\\/\"},\"wordCount\":125,\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/infos-1.jpg\",\"articleSection\":[\"Sc gestion\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\\\/\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\\\/\",\"name\":\"Information pour les \u00e9tudiants de L1, groupes: 21\\\/22\\\/ 23\\\/24\\\/29\\\/30. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/infos-1.jpg\",\"datePublished\":\"2026-04-11T18:50:50+00:00\",\"dateModified\":\"2026-04-11T18:55:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/infos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/infos-1.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Information pour les \u00e9tudiants de L1, groupes: 21\\\/22\\\/ 23\\\/24\\\/29\\\/30.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\",\"name\":\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"description\":\"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\",\"name\":\"FSECSG\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/author\\\/fsecsg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Information pour les \u00e9tudiants de L1, groupes: 21\/22\/ 23\/24\/29\/30. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/","og_locale":"fr_FR","og_type":"article","og_title":"Information pour les \u00e9tudiants de L1, groupes: 21\/22\/ 23\/24\/29\/30. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","og_description":"&nbsp; Les \u00e9tudiants de premi\u00e8re ann\u00e9e LMD groupe 21\/22\/23\/24\/29\/30 sont inform\u00e9s que l'examen TD de statistiques 2 est programm\u00e9 dans les s\u00e9ances de TD demain dimanche 12\/04\/2026 et \u00a0apr\u00e8s demain 13\/04\/2026.","og_url":"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/","og_site_name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","article_published_time":"2026-04-11T18:50:50+00:00","article_modified_time":"2026-04-11T18:55:24+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/infos-1.jpg","type":"image\/jpeg"}],"author":"FSECSG","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"FSECSG","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/#article","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/"},"author":{"name":"FSECSG","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"headline":"Information pour les \u00e9tudiants de L1, groupes: 21\/22\/ 23\/24\/29\/30.","datePublished":"2026-04-11T18:50:50+00:00","dateModified":"2026-04-11T18:55:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/"},"wordCount":125,"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/infos-1.jpg","articleSection":["Sc gestion"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/","url":"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/","name":"Information pour les \u00e9tudiants de L1, groupes: 21\/22\/ 23\/24\/29\/30. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/#primaryimage"},"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/infos-1.jpg","datePublished":"2026-04-11T18:50:50+00:00","dateModified":"2026-04-11T18:55:24+00:00","author":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"breadcrumb":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/#primaryimage","url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/infos-1.jpg","contentUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2022\/12\/infos-1.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.ummto.dz\/fsecsg\/information-pour-les-etudiants-de-l1-groupes-21-22-23-24-29-30\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ummto.dz\/fsecsg\/"},{"@type":"ListItem","position":2,"name":"Information pour les \u00e9tudiants de L1, groupes: 21\/22\/ 23\/24\/29\/30."}]},{"@type":"WebSite","@id":"https:\/\/www.ummto.dz\/fsecsg\/#website","url":"https:\/\/www.ummto.dz\/fsecsg\/","name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","description":"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ummto.dz\/fsecsg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3","name":"FSECSG","url":"https:\/\/www.ummto.dz\/fsecsg\/author\/fsecsg\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/93709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/comments?post=93709"}],"version-history":[{"count":3,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/93709\/revisions"}],"predecessor-version":[{"id":93712,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/93709\/revisions\/93712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media\/69459"}],"wp:attachment":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media?parent=93709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/categories?post=93709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/tags?post=93709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}