{"id":94200,"date":"2026-05-05T12:39:10","date_gmt":"2026-05-05T10:39:10","guid":{"rendered":"https:\/\/www.ummto.dz\/fsecsg\/?p=94200"},"modified":"2026-05-05T13:01:20","modified_gmt":"2026-05-05T11:01:20","slug":"liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs","status":"publish","type":"post","link":"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/","title":{"rendered":"Liste des \u00e9tudiants du d\u00e9partement sces commerciales selon les lieux d&rsquo;examens des semestres pairs."},"content":{"rendered":"[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbText\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb min_height=\u00a0\u00bb184px\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<p><strong><a href=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2026\/05\/Listes-L1.pdf\" rel=\"attachment wp-att-94205\">-Listes L1<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2026\/05\/Listes-L2-SC.pdf\" rel=\"attachment wp-att-94206\">-Listes L2 SC<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2026\/05\/Listes-L3-FCI.pdf\" rel=\"attachment wp-att-94207\">-Listes L3 FCI<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2026\/05\/Listes-L3-Marketing.pdf\" rel=\"attachment wp-att-94208\">-Listes L3 Marketing<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2026\/05\/Listes-M-1-Marketing.pdf\" rel=\"attachment wp-att-94209\">-Listes M 1 Marketing<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2026\/05\/Listes-M-1-CF.pdf\" rel=\"attachment wp-att-94210\">-Listes M 1 CF<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2026\/05\/Listes-M-1-MS.pdf\" rel=\"attachment wp-att-94212\">-Listes M 1 MS<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2026\/05\/Listes-M1-FCI.pdf\" rel=\"attachment wp-att-94213\">-Listes M1 FCI<\/a><\/strong><\/p>\n<p><strong><\/strong><\/p>\n<p><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]","protected":false},"excerpt":{"rendered":"<p>-Listes L1 -Listes L2 SC -Listes L3 FCI -Listes L3 Marketing -Listes M 1 Marketing -Listes M 1 CF -Listes M 1 MS -Listes M1 FCI<\/p>\n","protected":false},"author":4,"featured_media":8430,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"categories":[23],"tags":[],"class_list":["post-94200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-new-dep-sc-commerciale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Liste des \u00e9tudiants du d\u00e9partement sces commerciales selon les lieux d&#039;examens des semestres pairs. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liste des \u00e9tudiants du d\u00e9partement sces commerciales selon les lieux d&#039;examens des semestres pairs. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"og:description\" content=\"-Listes L1 -Listes L2 SC -Listes L3 FCI -Listes L3 Marketing -Listes M 1 Marketing -Listes M 1 CF -Listes M 1 MS -Listes M1 FCI\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/\" \/>\n<meta property=\"og:site_name\" content=\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-05T10:39:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T11:01:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2018\/10\/examen-algemeen-320x320.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"247\" \/>\n\t<meta property=\"og:image:height\" content=\"159\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FSECSG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"FSECSG\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\\\/\"},\"author\":{\"name\":\"FSECSG\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"headline\":\"Liste des \u00e9tudiants du d\u00e9partement sces commerciales selon les lieux d&rsquo;examens des semestres pairs.\",\"datePublished\":\"2026-05-05T10:39:10+00:00\",\"dateModified\":\"2026-05-05T11:01:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\\\/\"},\"wordCount\":127,\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/examen-algemeen-320x320.jpg\",\"articleSection\":[\"Sc commerciale\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\\\/\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\\\/\",\"name\":\"Liste des \u00e9tudiants du d\u00e9partement sces commerciales selon les lieux d'examens des semestres pairs. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/examen-algemeen-320x320.jpg\",\"datePublished\":\"2026-05-05T10:39:10+00:00\",\"dateModified\":\"2026-05-05T11:01:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/examen-algemeen-320x320.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/examen-algemeen-320x320.jpg\",\"width\":247,\"height\":159},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Liste des \u00e9tudiants du d\u00e9partement sces commerciales selon les lieux d&rsquo;examens des semestres pairs.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\",\"name\":\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"description\":\"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\",\"name\":\"FSECSG\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/author\\\/fsecsg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Liste des \u00e9tudiants du d\u00e9partement sces commerciales selon les lieux d'examens des semestres pairs. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/","og_locale":"fr_FR","og_type":"article","og_title":"Liste des \u00e9tudiants du d\u00e9partement sces commerciales selon les lieux d'examens des semestres pairs. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","og_description":"-Listes L1 -Listes L2 SC -Listes L3 FCI -Listes L3 Marketing -Listes M 1 Marketing -Listes M 1 CF -Listes M 1 MS -Listes M1 FCI","og_url":"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/","og_site_name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","article_published_time":"2026-05-05T10:39:10+00:00","article_modified_time":"2026-05-05T11:01:20+00:00","og_image":[{"width":247,"height":159,"url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2018\/10\/examen-algemeen-320x320.jpg","type":"image\/jpeg"}],"author":"FSECSG","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"FSECSG"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/#article","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/"},"author":{"name":"FSECSG","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"headline":"Liste des \u00e9tudiants du d\u00e9partement sces commerciales selon les lieux d&rsquo;examens des semestres pairs.","datePublished":"2026-05-05T10:39:10+00:00","dateModified":"2026-05-05T11:01:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/"},"wordCount":127,"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2018\/10\/examen-algemeen-320x320.jpg","articleSection":["Sc commerciale"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/","url":"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/","name":"Liste des \u00e9tudiants du d\u00e9partement sces commerciales selon les lieux d'examens des semestres pairs. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/#primaryimage"},"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2018\/10\/examen-algemeen-320x320.jpg","datePublished":"2026-05-05T10:39:10+00:00","dateModified":"2026-05-05T11:01:20+00:00","author":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"breadcrumb":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/#primaryimage","url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2018\/10\/examen-algemeen-320x320.jpg","contentUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2018\/10\/examen-algemeen-320x320.jpg","width":247,"height":159},{"@type":"BreadcrumbList","@id":"https:\/\/www.ummto.dz\/fsecsg\/liste-des-etudiants-du-departement-sces-commerciales-selon-les-lieux-dexamens-des-semestres-pairs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ummto.dz\/fsecsg\/"},{"@type":"ListItem","position":2,"name":"Liste des \u00e9tudiants du d\u00e9partement sces commerciales selon les lieux d&rsquo;examens des semestres pairs."}]},{"@type":"WebSite","@id":"https:\/\/www.ummto.dz\/fsecsg\/#website","url":"https:\/\/www.ummto.dz\/fsecsg\/","name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","description":"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ummto.dz\/fsecsg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3","name":"FSECSG","url":"https:\/\/www.ummto.dz\/fsecsg\/author\/fsecsg\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/94200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/comments?post=94200"}],"version-history":[{"count":3,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/94200\/revisions"}],"predecessor-version":[{"id":94214,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/94200\/revisions\/94214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media\/8430"}],"wp:attachment":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media?parent=94200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/categories?post=94200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/tags?post=94200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}