{"id":94295,"date":"2026-05-13T11:58:20","date_gmt":"2026-05-13T09:58:20","guid":{"rendered":"https:\/\/www.ummto.dz\/fsecsg\/?p=94295"},"modified":"2026-05-13T12:05:24","modified_gmt":"2026-05-13T10:05:24","slug":"soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas","status":"publish","type":"post","link":"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/","title":{"rendered":"Avis de soutenance de th\u00e8se de doctorat en Sciences Economiques de l&rsquo;imp\u00e9trant :\u00a0HADDADI Lounas."},"content":{"rendered":"\n[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbText\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb min_height=\u00a0\u00bb178px\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<p><strong><a href=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2026\/05\/Affichage-St-HADDADI-Lounas.pdf\"><img decoding=\"async\" src=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2026\/05\/Affichage-St-HADDADI-Lounas.webp\" width=\"1700\" height=\"2339\" alt=\"\" class=\"wp-image-94299 alignnone size-full\" srcset=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2026\/05\/Affichage-St-HADDADI-Lounas.webp 1700w, https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2026\/05\/Affichage-St-HADDADI-Lounas-1280x1761.webp 1280w, https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2026\/05\/Affichage-St-HADDADI-Lounas-980x1348.webp 980w, https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2026\/05\/Affichage-St-HADDADI-Lounas-480x660.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1700px, 100vw\" \/><\/a><\/strong><\/p>\n<p><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":132,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-94295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avis de soutenance de th\u00e8se de doctorat en Sciences Economiques de l&#039;imp\u00e9trant :\u00a0HADDADI Lounas. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avis de soutenance de th\u00e8se de doctorat en Sciences Economiques de l&#039;imp\u00e9trant :\u00a0HADDADI Lounas. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/\" \/>\n<meta property=\"og:site_name\" content=\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T09:58:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:05:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2018\/01\/doctorat-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"100\" \/>\n\t<meta property=\"og:image:height\" content=\"100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"FSECSG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"FSECSG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\\\/\"},\"author\":{\"name\":\"FSECSG\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"headline\":\"Avis de soutenance de th\u00e8se de doctorat en Sciences Economiques de l&rsquo;imp\u00e9trant :\u00a0HADDADI Lounas.\",\"datePublished\":\"2026-05-13T09:58:20+00:00\",\"dateModified\":\"2026-05-13T10:05:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\\\/\"},\"wordCount\":106,\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/doctorat-1.png\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\\\/\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\\\/\",\"name\":\"Avis de soutenance de th\u00e8se de doctorat en Sciences Economiques de l'imp\u00e9trant :\u00a0HADDADI Lounas. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/doctorat-1.png\",\"datePublished\":\"2026-05-13T09:58:20+00:00\",\"dateModified\":\"2026-05-13T10:05:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/doctorat-1.png\",\"contentUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/doctorat-1.png\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avis de soutenance de th\u00e8se de doctorat en Sciences Economiques de l&rsquo;imp\u00e9trant :\u00a0HADDADI Lounas.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#website\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/\",\"name\":\"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion\",\"description\":\"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/#\\\/schema\\\/person\\\/c5f2e51b7d49f0febe1a7d8e53b452e3\",\"name\":\"FSECSG\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fsecsg\\\/author\\\/fsecsg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avis de soutenance de th\u00e8se de doctorat en Sciences Economiques de l'imp\u00e9trant :\u00a0HADDADI Lounas. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/","og_locale":"fr_FR","og_type":"article","og_title":"Avis de soutenance de th\u00e8se de doctorat en Sciences Economiques de l'imp\u00e9trant :\u00a0HADDADI Lounas. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","og_url":"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/","og_site_name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","article_published_time":"2026-05-13T09:58:20+00:00","article_modified_time":"2026-05-13T10:05:24+00:00","og_image":[{"width":100,"height":100,"url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2018\/01\/doctorat-1.png","type":"image\/png"}],"author":"FSECSG","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"FSECSG","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/#article","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/"},"author":{"name":"FSECSG","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"headline":"Avis de soutenance de th\u00e8se de doctorat en Sciences Economiques de l&rsquo;imp\u00e9trant :\u00a0HADDADI Lounas.","datePublished":"2026-05-13T09:58:20+00:00","dateModified":"2026-05-13T10:05:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/"},"wordCount":106,"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2018\/01\/doctorat-1.png","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/","url":"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/","name":"Avis de soutenance de th\u00e8se de doctorat en Sciences Economiques de l'imp\u00e9trant :\u00a0HADDADI Lounas. - Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/#primaryimage"},"image":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2018\/01\/doctorat-1.png","datePublished":"2026-05-13T09:58:20+00:00","dateModified":"2026-05-13T10:05:24+00:00","author":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3"},"breadcrumb":{"@id":"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/#primaryimage","url":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2018\/01\/doctorat-1.png","contentUrl":"https:\/\/www.ummto.dz\/fsecsg\/wp-content\/uploads\/2018\/01\/doctorat-1.png","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.ummto.dz\/fsecsg\/soutenance-de-these-de-doctorat-en-sciences-economiques-de-limpetrant-haddadi-lounas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ummto.dz\/fsecsg\/"},{"@type":"ListItem","position":2,"name":"Avis de soutenance de th\u00e8se de doctorat en Sciences Economiques de l&rsquo;imp\u00e9trant :\u00a0HADDADI Lounas."}]},{"@type":"WebSite","@id":"https:\/\/www.ummto.dz\/fsecsg\/#website","url":"https:\/\/www.ummto.dz\/fsecsg\/","name":"Facult\u00e9 des Sciences Economiques, Commerciales et des Sciences de Gestion","description":"Universit\u00e9 Mouloud Mammeri de Tizi Ouzou","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ummto.dz\/fsecsg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ummto.dz\/fsecsg\/#\/schema\/person\/c5f2e51b7d49f0febe1a7d8e53b452e3","name":"FSECSG","url":"https:\/\/www.ummto.dz\/fsecsg\/author\/fsecsg\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/94295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/comments?post=94295"}],"version-history":[{"count":4,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/94295\/revisions"}],"predecessor-version":[{"id":94302,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/posts\/94295\/revisions\/94302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media\/132"}],"wp:attachment":[{"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/media?parent=94295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/categories?post=94295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ummto.dz\/fsecsg\/wp-json\/wp\/v2\/tags?post=94295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}