{"id":6486,"date":"2024-07-02T13:13:44","date_gmt":"2024-07-02T11:13:44","guid":{"rendered":"https:\/\/www.ummto.dz\/fshs\/?p=6486"},"modified":"2024-07-02T13:13:47","modified_gmt":"2024-07-02T11:13:47","slug":"avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux","status":"publish","type":"post","link":"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/","title":{"rendered":"Avis aux enseignants du d\u00e9partement des sciences sociales (fiches de v\u0153ux)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.ummto.dz\/fshs\/wp-content\/uploads\/2024\/07\/avis_1-scaled.jpg\" alt=\"\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":2899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[7,11],"tags":[],"class_list":["post-6486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-new_sciences_sociales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avis aux enseignants du d\u00e9partement des sciences sociales (fiches de v\u0153ux) - Facult\u00e9 des Sciences Humaines et Sociales<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avis aux enseignants du d\u00e9partement des sciences sociales (fiches de v\u0153ux) - Facult\u00e9 des Sciences Humaines et Sociales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/\" \/>\n<meta property=\"og:site_name\" content=\"Facult\u00e9 des Sciences Humaines et Sociales\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-02T11:13:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-02T11:13:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ummto.dz\/fshs\/wp-content\/uploads\/2021\/11\/avis-e.png\" \/>\n\t<meta property=\"og:image:width\" content=\"255\" \/>\n\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"FSHS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"FSHS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\\\/\"},\"author\":{\"name\":\"FSHS\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/#\\\/schema\\\/person\\\/a56a254f106e96144ed6a6b3904e1922\"},\"headline\":\"Avis aux enseignants du d\u00e9partement des sciences sociales (fiches de v\u0153ux)\",\"datePublished\":\"2024-07-02T11:13:44+00:00\",\"dateModified\":\"2024-07-02T11:13:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\\\/\"},\"wordCount\":13,\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/avis-e.png\",\"articleSection\":[\"Actualit\u00e9\",\"sciences_sociales\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\\\/\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\\\/\",\"name\":\"Avis aux enseignants du d\u00e9partement des sciences sociales (fiches de v\u0153ux) - Facult\u00e9 des Sciences Humaines et Sociales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/avis-e.png\",\"datePublished\":\"2024-07-02T11:13:44+00:00\",\"dateModified\":\"2024-07-02T11:13:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/#\\\/schema\\\/person\\\/a56a254f106e96144ed6a6b3904e1922\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/avis-e.png\",\"contentUrl\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/avis-e.png\",\"width\":255,\"height\":224},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avis aux enseignants du d\u00e9partement des sciences sociales (fiches de v\u0153ux)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/#website\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/\",\"name\":\"Facult\u00e9 des Sciences Humaines et Sociales\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/#\\\/schema\\\/person\\\/a56a254f106e96144ed6a6b3904e1922\",\"name\":\"FSHS\",\"url\":\"https:\\\/\\\/www.ummto.dz\\\/fshs\\\/author\\\/fshs\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avis aux enseignants du d\u00e9partement des sciences sociales (fiches de v\u0153ux) - Facult\u00e9 des Sciences Humaines et Sociales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/","og_locale":"fr_FR","og_type":"article","og_title":"Avis aux enseignants du d\u00e9partement des sciences sociales (fiches de v\u0153ux) - Facult\u00e9 des Sciences Humaines et Sociales","og_url":"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/","og_site_name":"Facult\u00e9 des Sciences Humaines et Sociales","article_published_time":"2024-07-02T11:13:44+00:00","article_modified_time":"2024-07-02T11:13:47+00:00","og_image":[{"width":255,"height":224,"url":"https:\/\/www.ummto.dz\/fshs\/wp-content\/uploads\/2021\/11\/avis-e.png","type":"image\/png"}],"author":"FSHS","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"FSHS","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/#article","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/"},"author":{"name":"FSHS","@id":"https:\/\/www.ummto.dz\/fshs\/#\/schema\/person\/a56a254f106e96144ed6a6b3904e1922"},"headline":"Avis aux enseignants du d\u00e9partement des sciences sociales (fiches de v\u0153ux)","datePublished":"2024-07-02T11:13:44+00:00","dateModified":"2024-07-02T11:13:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/"},"wordCount":13,"image":{"@id":"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fshs\/wp-content\/uploads\/2021\/11\/avis-e.png","articleSection":["Actualit\u00e9","sciences_sociales"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/","url":"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/","name":"Avis aux enseignants du d\u00e9partement des sciences sociales (fiches de v\u0153ux) - Facult\u00e9 des Sciences Humaines et Sociales","isPartOf":{"@id":"https:\/\/www.ummto.dz\/fshs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/#primaryimage"},"image":{"@id":"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ummto.dz\/fshs\/wp-content\/uploads\/2021\/11\/avis-e.png","datePublished":"2024-07-02T11:13:44+00:00","dateModified":"2024-07-02T11:13:47+00:00","author":{"@id":"https:\/\/www.ummto.dz\/fshs\/#\/schema\/person\/a56a254f106e96144ed6a6b3904e1922"},"breadcrumb":{"@id":"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/#primaryimage","url":"https:\/\/www.ummto.dz\/fshs\/wp-content\/uploads\/2021\/11\/avis-e.png","contentUrl":"https:\/\/www.ummto.dz\/fshs\/wp-content\/uploads\/2021\/11\/avis-e.png","width":255,"height":224},{"@type":"BreadcrumbList","@id":"https:\/\/www.ummto.dz\/fshs\/avis-aux-enseignants-du-departement-des-sciences-sociales-fiches-de-voeux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ummto.dz\/fshs\/"},{"@type":"ListItem","position":2,"name":"Avis aux enseignants du d\u00e9partement des sciences sociales (fiches de v\u0153ux)"}]},{"@type":"WebSite","@id":"https:\/\/www.ummto.dz\/fshs\/#website","url":"https:\/\/www.ummto.dz\/fshs\/","name":"Facult\u00e9 des Sciences Humaines et Sociales","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ummto.dz\/fshs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ummto.dz\/fshs\/#\/schema\/person\/a56a254f106e96144ed6a6b3904e1922","name":"FSHS","url":"https:\/\/www.ummto.dz\/fshs\/author\/fshs\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ummto.dz\/fshs\/wp-json\/wp\/v2\/posts\/6486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ummto.dz\/fshs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ummto.dz\/fshs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fshs\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fshs\/wp-json\/wp\/v2\/comments?post=6486"}],"version-history":[{"count":1,"href":"https:\/\/www.ummto.dz\/fshs\/wp-json\/wp\/v2\/posts\/6486\/revisions"}],"predecessor-version":[{"id":6487,"href":"https:\/\/www.ummto.dz\/fshs\/wp-json\/wp\/v2\/posts\/6486\/revisions\/6487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ummto.dz\/fshs\/wp-json\/wp\/v2\/media\/2899"}],"wp:attachment":[{"href":"https:\/\/www.ummto.dz\/fshs\/wp-json\/wp\/v2\/media?parent=6486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ummto.dz\/fshs\/wp-json\/wp\/v2\/categories?post=6486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ummto.dz\/fshs\/wp-json\/wp\/v2\/tags?post=6486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}